{"id":15928,"date":"2026-05-12T14:35:27","date_gmt":"2026-05-12T14:35:27","guid":{"rendered":"https:\/\/www.aeplima.pt\/aeplima\/?p=15928"},"modified":"2026-05-12T14:35:31","modified_gmt":"2026-05-12T14:35:31","slug":"ingles-visita-de-estudo-a-londres","status":"publish","type":"post","link":"https:\/\/www.aeplima.pt\/aeplima\/2026\/05\/12\/ingles-visita-de-estudo-a-londres\/","title":{"rendered":"Ingl\u00eas &#8211; Visita de Estudo a Londres"},"content":{"rendered":"\n<p>Entre os <strong>dias 25 e 28 de mar\u00e7o<\/strong>, a turma <strong>12.\u00ba D<\/strong> realizou uma <strong>viagem de estudo a Londres<\/strong>, no \u00e2mbito da disciplina de Ingl\u00eas, acompanhada pela docente Mary Nogueira e pelo diretor de turma, Eduardo Loureiro. A atividade foi vivida por todos com grande entusiasmo, interesse, curiosidade e esp\u00edrito de descoberta.<\/p>\n\n\n\n<p>A estadia teve in\u00edcio com a chegada ao Astor Kensington Hostel, seguindo-se um primeiro passeio pelo Hyde Park. Nos dias seguintes, os alunos tiveram a oportunidade de explorar alguns dos locais mais emblem\u00e1ticos da cidade, como a Tower Bridge, o British Museum \u2014 onde puderam apreciar obras e esculturas de civiliza\u00e7\u00f5es antigas, nomeadamente eg\u00edpcia, grega e mesopot\u00e2mica \u2014 e o Madame Tussauds, que despertou particular interesse pelas figuras de cera de personalidades conhecidas, bem como pela recria\u00e7\u00e3o imersiva de momentos e ambientes hist\u00f3ricos, permitindo uma verdadeira \u201cviagem\u201d \u00e0 Londres do passado. O roteiro incluiu ainda Piccadilly Circus, Chinatown, Trafalgar Square e a National Gallery.<\/p>\n\n\n\n<p>No terceiro dia, os alunos passearam pelo St. James\u2019s Park e assistiram \u00e0 Cerim\u00f3nia da Troca da Guarda Real, junto ao Pal\u00e1cio de Buckingham. De seguida, visitaram o Natural History Museum, onde se destacaram as exposi\u00e7\u00f5es dedicadas aos dinossauros e \u00e0 evolu\u00e7\u00e3o da Terra. A tarde foi dedicada \u00e0 descoberta de Camden Town e terminou em Covent Garden, onde a turma assistiu a um espet\u00e1culo de rua que animou o ambiente e proporcionou um momento de grande entusiasmo.<\/p>\n\n\n\n<p>Na manh\u00e3 do dia seguinte, os alunos regressaram a Portugal enriquecidos por uma experi\u00eancia cultural inesquec\u00edvel, que lhes permitiu contactar diretamente com a l\u00edngua inglesa, alargar horizontes e aprofundar o conhecimento sobre a cultura brit\u00e2nica.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.aeplima.pt\/aeplima\/wp-content\/uploads\/2026\/05\/london-trip-12oD-1024x768.jpeg\" alt=\"\" class=\"wp-image-15929\" srcset=\"https:\/\/www.aeplima.pt\/aeplima\/wp-content\/uploads\/2026\/05\/london-trip-12oD-1024x768.jpeg 1024w, https:\/\/www.aeplima.pt\/aeplima\/wp-content\/uploads\/2026\/05\/london-trip-12oD-300x225.jpeg 300w, https:\/\/www.aeplima.pt\/aeplima\/wp-content\/uploads\/2026\/05\/london-trip-12oD-768x576.jpeg 768w, https:\/\/www.aeplima.pt\/aeplima\/wp-content\/uploads\/2026\/05\/london-trip-12oD-1536x1152.jpeg 1536w, https:\/\/www.aeplima.pt\/aeplima\/wp-content\/uploads\/2026\/05\/london-trip-12oD.jpeg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Entre os dias 25 e 28 de mar\u00e7o, a turma 12.\u00ba D realizou uma viagem de estudo a Londres, no \u00e2mbito da disciplina de Ingl\u00eas, acompanhada pela docente Mary Nogueira e pelo diretor de turma, Eduardo Loureiro. A atividade foi vivida por todos com grande entusiasmo, interesse, curiosidade e esp\u00edrito de descoberta. A estadia teve [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":15929,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41,4],"tags":[],"class_list":["post-15928","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espl","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.aeplima.pt\/aeplima\/wp-json\/wp\/v2\/posts\/15928","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aeplima.pt\/aeplima\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aeplima.pt\/aeplima\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aeplima.pt\/aeplima\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aeplima.pt\/aeplima\/wp-json\/wp\/v2\/comments?post=15928"}],"version-history":[{"count":1,"href":"https:\/\/www.aeplima.pt\/aeplima\/wp-json\/wp\/v2\/posts\/15928\/revisions"}],"predecessor-version":[{"id":15930,"href":"https:\/\/www.aeplima.pt\/aeplima\/wp-json\/wp\/v2\/posts\/15928\/revisions\/15930"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aeplima.pt\/aeplima\/wp-json\/wp\/v2\/media\/15929"}],"wp:attachment":[{"href":"https:\/\/www.aeplima.pt\/aeplima\/wp-json\/wp\/v2\/media?parent=15928"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aeplima.pt\/aeplima\/wp-json\/wp\/v2\/categories?post=15928"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aeplima.pt\/aeplima\/wp-json\/wp\/v2\/tags?post=15928"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}